{"id":28945,"date":"2026-03-30T13:40:10","date_gmt":"2026-03-30T13:40:10","guid":{"rendered":"https:\/\/wsa.ch\/de\/?post_type=catalog_product&#038;p=28945"},"modified":"2026-04-01T11:19:48","modified_gmt":"2026-04-01T11:19:48","slug":"fuste","status":"publish","type":"catalog_product","link":"https:\/\/wsa.ch\/de\/produkte\/einrichtung\/tischsysteme\/meetingtische\/fuste","title":{"rendered":"Fuste"},"content":{"rendered":"\n<p>FUSTE ist ein hochwertiger Tisch aus massiver Eiche, entwickelt f\u00fcr professionelle Umgebungen, in denen Robustheit, klare Linien und warme Materialit\u00e4t gefragt sind. Die organisch geformte Tischplatte verleiht dem Tisch eine weiche, zeitlose Pr\u00e4senz, w\u00e4hrend die vier fein gerillten Tischbeine f\u00fcr eine ruhige vertikale Struktur sorgen. Die Beine k\u00f6nnen in zwei Positionen konfiguriert werden, um unterschiedliche Raumsituationen und Nutzungen zu unterst\u00fctzen.<\/p>\n\n\n\n<p>F\u00fcr den Einsatz in Meeting- und Projektbereichen kann FUSTE mit einem integrierten Elektrifizierungssystem ausgestattet werden. Die Kabelf\u00fchrung erfolgt verdeckt durch eines der Tischbeine, wodurch ein aufger\u00e4umtes, professionelles Erscheinungsbild gew\u00e4hrleistet wird.<\/p>\n\n\n\n<p>Der Tisch kombiniert nat\u00fcrliche Materialwirkung mit funktionaler Effizienz \u2013 ideal f\u00fcr Besprechungsr\u00e4ume, offene Arbeitszonen und repr\u00e4sentative Empfangsbereiche.<\/p>\n","protected":false},"featured_media":28974,"parent":6747,"menu_order":386,"template":"","furnishing_brand":[46],"class_list":["post-28945","catalog_product","type-catalog_product","status-publish","has-post-thumbnail","hentry","furnishing_brand-viccarbe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fuste | WSA | B\u00fcroplanung - B\u00fcroeinrichtung<\/title>\n<meta name=\"description\" content=\"WSA - Ihr Spezialist f\u00fcr B\u00fcroplanung. Fuste - mehr erfahren.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wsa.ch\/de\/produkte\/einrichtung\/tischsysteme\/meetingtische\/fuste\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fuste | WSA | B\u00fcroplanung - B\u00fcroeinrichtung\" \/>\n<meta property=\"og:description\" content=\"WSA - Ihr Spezialist f\u00fcr B\u00fcroplanung. Fuste - mehr erfahren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wsa.ch\/de\/produkte\/einrichtung\/tischsysteme\/meetingtische\/fuste\" \/>\n<meta property=\"og:site_name\" content=\"WSA\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T11:19:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wsa.ch\/de\/wp-content\/uploads\/2026\/03\/23-0210919-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1374\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\">\n\t<meta name=\"twitter:data1\" content=\"0\u00a0Minuten\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wsa.ch\/de\/#website\",\"url\":\"https:\/\/wsa.ch\/de\/\",\"name\":\"WSA\",\"description\":\"WSA is a leading supplier of modern office and communications environments\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/wsa.ch\/de\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/wsa.ch\/de\/produkte\/einrichtung\/tischsysteme\/meetingtische\/fuste#primaryimage\",\"inLanguage\":\"de\",\"url\":\"https:\/\/wsa.ch\/de\/wp-content\/uploads\/2026\/03\/23-0210919-scaled.jpg\",\"width\":2560,\"height\":1374},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wsa.ch\/de\/produkte\/einrichtung\/tischsysteme\/meetingtische\/fuste#webpage\",\"url\":\"https:\/\/wsa.ch\/de\/produkte\/einrichtung\/tischsysteme\/meetingtische\/fuste\",\"name\":\"Fuste | WSA | B\\u00fcroplanung - B\\u00fcroeinrichtung\",\"isPartOf\":{\"@id\":\"https:\/\/wsa.ch\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/wsa.ch\/de\/produkte\/einrichtung\/tischsysteme\/meetingtische\/fuste#primaryimage\"},\"datePublished\":\"2026-03-30T13:40:10+00:00\",\"dateModified\":\"2026-04-01T11:19:48+00:00\",\"description\":\"WSA - Ihr Spezialist f\\u00fcr B\\u00fcroplanung. Fuste - mehr erfahren.\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wsa.ch\/de\/produkte\/einrichtung\/tischsysteme\/meetingtische\/fuste\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/wsa.ch\/de\/wp-json\/wp\/v2\/catalog_product\/28945"}],"collection":[{"href":"https:\/\/wsa.ch\/de\/wp-json\/wp\/v2\/catalog_product"}],"about":[{"href":"https:\/\/wsa.ch\/de\/wp-json\/wp\/v2\/types\/catalog_product"}],"version-history":[{"count":3,"href":"https:\/\/wsa.ch\/de\/wp-json\/wp\/v2\/catalog_product\/28945\/revisions"}],"predecessor-version":[{"id":28952,"href":"https:\/\/wsa.ch\/de\/wp-json\/wp\/v2\/catalog_product\/28945\/revisions\/28952"}],"up":[{"embeddable":true,"href":"https:\/\/wsa.ch\/de\/wp-json\/wp\/v2\/catalog_product\/6747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wsa.ch\/de\/wp-json\/wp\/v2\/media\/28974"}],"wp:attachment":[{"href":"https:\/\/wsa.ch\/de\/wp-json\/wp\/v2\/media?parent=28945"}],"wp:term":[{"taxonomy":"furnishing_brand","embeddable":true,"href":"https:\/\/wsa.ch\/de\/wp-json\/wp\/v2\/furnishing_brand?post=28945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}